{"id":76,"date":"2021-01-27T05:03:58","date_gmt":"2021-01-27T10:03:58","guid":{"rendered":"https:\/\/ifingerstudio.com\/wellpress\/?page_id=76"},"modified":"2024-12-10T16:50:44","modified_gmt":"2024-12-10T16:50:44","slug":"servizi-di-monitoraggio-remoto-dei-pazienti","status":"publish","type":"page","link":"https:\/\/censonhealth.com\/it\/remote-patient-monitoring-services\/","title":{"rendered":"Servizi di monitoraggio remoto dei pazienti"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"76\" class=\"elementor elementor-76\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f3689b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f3689b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff04007\" data-id=\"ff04007\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be736d5 elementor-widget elementor-widget-section-head-two\" data-id=\"be736d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section-head-two.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"section-title-three text-center\">\r\n            \t            <h6 > Smartphone Monitoraggio a domicilio <\/h6>\r\n                        \t            <h2 > Servizi di fornitura di monitoraggio remoto dei pazienti <\/h2>\r\n            \r\n            \t\t\t\t<p class=\"line\">Grazie a una tecnologia semplice, la piattaforma di CENSON, dotata di smartphone, fornisce servizi di monitoraggio remoto dei pazienti.  Ci\u00f2 consente di migliorare l'accuratezza diagnostica, di intervenire pi\u00f9 precocemente e di ottenere risultati migliori in termini di salute.<\/p>\r\n                  <\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f066cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f066cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc93648\" data-id=\"fc93648\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7b0f2c elementor-widget elementor-widget-section-service\" data-id=\"e7b0f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section-service.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t<div class=\"row\">\n\t\t\n\t\t\n\t\t\t<div class=\"col-lg-4 col-md-6\">\n                <div class=\"services-item text-center mb-30\">\n                    <div class=\"services-overlay-icon\"><i class=\"flaticon-capsules\"><\/i><\/div>\n                    <div class=\"service-content\">\n                    \t                        \t<h6 class=\"count\">01<\/h6>\n                        \n                    \t                        \t<h3><a href=\"https:\/\/censonhealth.com\/it\/service\/medical-care\/\">Assistenza medica<\/a><\/h3>\n\t\t           \t\t\n                    \t                        \t<p>Costruite il vostro modello di erogazione di cure mediche e sanitarie per incontrare le persone dove vivono e utilizzando il loro smartphone.<\/p>\n                                            <\/div>\n                    <div class=\"single-services-style-one-icons\">\n\t\t\t            \t\t\t              \t<div class=\"service-icon\">\n\t\t\t                \t<i class=\"flaticon-capsules\"><\/i>\n\t\t\t              \t<\/div>\n\t\t\t            \t\t        \t<\/div>\n                <\/div>\n\t\t\t<\/div>\n\n\t\t   \t\t\n\t\t\n\t\t\t<div class=\"col-lg-4 col-md-6\">\n                <div class=\"services-item text-center mb-30\">\n                    <div class=\"services-overlay-icon\"><i class=\"flaticon-old-man\"><\/i><\/div>\n                    <div class=\"service-content\">\n                    \t                        \t<h6 class=\"count\">02<\/h6>\n                        \n                    \t                        \t<h3><a href=\"https:\/\/censonhealth.com\/it\/service\/resident-care\/\">Assistenza ai residenti<\/a><\/h3>\n\t\t           \t\t\n                    \t                        \t<p>Costruite il vostro modello di assistenza ai residenti per incontrare le persone dove vivono e utilizzando il loro smartphone.<\/p>\n                                            <\/div>\n                    <div class=\"single-services-style-one-icons\">\n\t\t\t            \t\t\t              \t<div class=\"service-icon\">\n\t\t\t                \t<i class=\"flaticon-old-man\"><\/i>\n\t\t\t              \t<\/div>\n\t\t\t            \t\t        \t<\/div>\n                <\/div>\n\t\t\t<\/div>\n\n\t\t   \t\t\n\t\t\n\t\t\t<div class=\"col-lg-4 col-md-6\">\n                <div class=\"services-item text-center mb-30\">\n                    <div class=\"services-overlay-icon\"><i class=\"flaticon-pinwheel\"><\/i><\/div>\n                    <div class=\"service-content\">\n                    \t                        \t<h6 class=\"count\">03<\/h6>\n                        \n                    \t                        \t<h3><a href=\"https:\/\/censonhealth.com\/it\/service\/independent-living\/\">Vita indipendente<\/a><\/h3>\n\t\t           \t\t\n                    \t                        \t<p>Costruite il vostro modello di assistenza medica e sanitaria per la vita indipendente per incontrare le persone dove vivono e utilizzando il loro smartphone.<\/p>\n                                            <\/div>\n                    <div class=\"single-services-style-one-icons\">\n\t\t\t            \t\t\t              \t<div class=\"service-icon\">\n\t\t\t                \t<i class=\"flaticon-pinwheel\"><\/i>\n\t\t\t              \t<\/div>\n\t\t\t            \t\t        \t<\/div>\n                <\/div>\n\t\t\t<\/div>\n\n\t\t   \t\t\n\t\t\n\t\t\t<div class=\"col-lg-4 col-md-6\">\n                <div class=\"services-item text-center mb-30\">\n                    <div class=\"services-overlay-icon\"><i class=\"flaticon-clock\"><\/i><\/div>\n                    <div class=\"service-content\">\n                    \t                        \t<h6 class=\"count\">04<\/h6>\n                        \n                    \t                        \t<h3><a href=\"https:\/\/censonhealth.com\/it\/service\/memory-care\/\">Assistenza alla memoria<\/a><\/h3>\n\t\t           \t\t\n                    \t                        \t<p>Costruite il vostro modello di erogazione di cure mediche e sanitarie per incontrare le persone dove vivono e utilizzando il loro smartphone.<\/p>\n                                            <\/div>\n                    <div class=\"single-services-style-one-icons\">\n\t\t\t            \t\t\t              \t<div class=\"service-icon\">\n\t\t\t                \t<i class=\"flaticon-clock\"><\/i>\n\t\t\t              \t<\/div>\n\t\t\t            \t\t        \t<\/div>\n                <\/div>\n\t\t\t<\/div>\n\n\t\t   \t\t\n\t\t\n\t\t\t<div class=\"col-lg-4 col-md-6\">\n                <div class=\"services-item text-center mb-30\">\n                    <div class=\"services-overlay-icon\"><i class=\"flaticon-doctor\"><\/i><\/div>\n                    <div class=\"service-content\">\n                    \t                        \t<h6 class=\"count\">05<\/h6>\n                        \n                    \t                        \t<h3><a href=\"https:\/\/censonhealth.com\/it\/service\/home-based-care\/\">Assistenza domiciliare<\/a><\/h3>\n\t\t           \t\t\n                    \t                        \t<p>Monitoraggio della salute tramite smartphone per il monitoraggio remoto del paziente e servizi sanitari digitali.  Costruite il vostro modello di assistenza domiciliare per incontrare le persone dove vivono, utilizzando il loro dispositivo di comunicazione preferito.<\/p>\n                                            <\/div>\n                    <div class=\"single-services-style-one-icons\">\n\t\t\t            \t\t\t              \t<div class=\"service-icon\">\n\t\t\t                \t<i class=\"flaticon-doctor\"><\/i>\n\t\t\t              \t<\/div>\n\t\t\t            \t\t        \t<\/div>\n                <\/div>\n\t\t\t<\/div>\n\n\t\t   \t\t\n\t\t\n\t\t\t<div class=\"col-lg-4 col-md-6\">\n                <div class=\"services-item text-center mb-30\">\n                    <div class=\"services-overlay-icon\"><i class=\"flaticon-friend\"><\/i><\/div>\n                    <div class=\"service-content\">\n                    \t                        \t<h6 class=\"count\">06<\/h6>\n                        \n                    \t                        \t<h3><a href=\"https:\/\/censonhealth.com\/it\/service\/facility-based-care\/\">Assistenza in struttura<\/a><\/h3>\n\t\t           \t\t\n                    \t                        \t<p>Costruite il vostro modello di erogazione dell'assistenza basato sulle strutture per incontrare le persone dove vivono, utilizzando il loro smartphone.<\/p>\n                                            <\/div>\n                    <div class=\"single-services-style-one-icons\">\n\t\t\t            \t\t\t              \t<div class=\"service-icon\">\n\t\t\t                \t<i class=\"flaticon-friend\"><\/i>\n\t\t\t              \t<\/div>\n\t\t\t            \t\t        \t<\/div>\n                <\/div>\n\t\t\t<\/div>\n\n\t\t   \t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-745a8d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"745a8d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c69611\" data-id=\"6c69611\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d2cd88 elementor-widget elementor-widget-heading\" data-id=\"6d2cd88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Testimonianze<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cb09ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cb09ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e9fd6f\" data-id=\"0e9fd6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9857174 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"9857174\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_masonry&quot;:&quot;yes&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15539 testimonial type-testimonial status-publish hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<div class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/censonhealth.com\/it\/testimonial\/real-results-from-real-patients\/\" target=\"&quot;_blank&quot;\">\n\t\t\t\tRisultati reali da parte di pazienti reali\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\"Sono rimasto stupito dalla facilit\u00e0 con cui ho potuto monitorare i miei parametri vitali e comunicare con il mio team sanitario attraverso la piattaforma di monitoraggio remoto dei pazienti di CENSON. Mi ha dato<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/censonhealth.com\/it\/testimonial\/real-results-from-real-patients\/\" aria-label=\"Ulteriori informazioni su Risultati reali di pazienti reali\" tabindex=\"-1\" target=\"_blank\">\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15543 testimonial type-testimonial status-publish hentry tag-remote-patient-monitoring\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<div class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/censonhealth.com\/it\/testimonial\/healthcare-providers-rave-about-censon\/\" target=\"&quot;_blank&quot;\">\n\t\t\t\tI fornitori di servizi sanitari sono entusiasti di CENSON\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\"La tecnologia di monitoraggio remoto dei pazienti di CENSON ha rivoluzionato il modo in cui forniamo assistenza ai nostri pazienti. I dati e gli avvisi in tempo reale ci hanno consentito di intervenire<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/censonhealth.com\/it\/testimonial\/healthcare-providers-rave-about-censon\/\" aria-label=\"Per saperne di pi\u00f9 su I fornitori di servizi sanitari apprezzano il CENSON\" tabindex=\"-1\" target=\"_blank\">\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-15547 testimonial type-testimonial status-publish hentry tag-remote-patient-monitoring\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<div class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/censonhealth.com\/it\/testimonial\/censons-impact-on-patient-outcomes\/\" target=\"&quot;_blank&quot;\">\n\t\t\t\tL'impatto del CENSON sui risultati dei pazienti\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\"La piattaforma di monitoraggio remoto dei pazienti di CENSON \u00e8 stata fondamentale per ridurre le riammissioni in ospedale dei nostri pazienti con patologie croniche. \u00c8 un gioco che cambia le carte in tavola!\". - Jane, coordinatore dell'assistenza<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/censonhealth.com\/it\/testimonial\/censons-impact-on-patient-outcomes\/\" aria-label=\"Per saperne di pi\u00f9 sull&#039;impatto del CENSON sui risultati dei pazienti\" tabindex=\"-1\" target=\"_blank\">\n\t\t\tContinua a leggere \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96df6b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96df6b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0376b49\" data-id=\"0376b49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9c1c505 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c1c505\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f9c92a\" data-id=\"7f9c92a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-081bcb6\" data-id=\"081bcb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a801e1b elementor-widget elementor-widget-section-head-two\" data-id=\"a801e1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section-head-two.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"section-title-three text-center\">\r\n            \t            <h6 > Blog <\/h6>\r\n                        \t            <h2 > Notizie <\/h2>\r\n            \r\n            \t\t\t\t<div class=\"default-line\"><\/div>\r\n\t\t\t      <\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-61ea850\" data-id=\"61ea850\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a6a283 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a6a283\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f3d25ef\" data-id=\"f3d25ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a6f81a elementor-widget elementor-widget-section-blog\" data-id=\"7a6f81a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<script type=\"text\/javascript\">\r\n   jQuery(document).ready(function(){\r\n\t\t\/\/ blog\r\n\t\tjQuery('.blog-post-thumb-active').slick({\r\n\t\t\tautoplay:true,\r\n\t\t\tautoplaySpeed:1500,\r\n\t\t\tdots: false,\r\n\t\t\tinfinite: true,\r\n\t\t\tarrows: true,\r\n\t\t\tspeed: 1500,\r\n\t\t\tslidesToShow: 1,\r\n\t\t\tslidesToScroll: 1,\r\n\t\t\tfade: true,\r\n\t\t\tprevArrow: '<button type=\"button\" class=\"slick-prev\"><i class=\"fas fa-arrow-left\"><\/i><\/button>',\r\n\t\t\tnextArrow: '<button type=\"button\" class=\"slick-next\"><i class=\"fas fa-arrow-right\"><\/i><\/button>',\r\n\t\t});\r\n   });\r\n<\/script> \r\n\r\n\t<div class=\"row\">\r\n\t\t\r\n\t<div class=\"col-lg-4 col-md-6 blog-shortcode\">\r\n\t\t<article id=\"post-16007\" class=\"post-16007 post type-post status-publish format-standard has-post-thumbnail hentry category-eldercare category-home-care category-remote-patient-monitoring category-senior-care tag-elderly tag-remote-patient-monitoring\">\r\n\t\t   \t<div class=\"blog-post-item bp-style-two v1\">\r\n\t\t   \t\t\t\t      \t\t\t\t         \t\t<div class=\"blog-post-thumb position-relative\">\r\n\t\t            \t\t<a href=\"https:\/\/censonhealth.com\/it\/my-remote-patient-monitoring-experience\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"770\" height=\"460\" src=\"https:\/\/censonhealth.com\/wp-content\/uploads\/2026\/05\/rpm-770x460.jpg\" class=\"attachment-wellpress-770-460 size-wellpress-770-460 wp-post-image\" alt=\"La mia esperienza con il monitoraggio remoto dei pazienti\" srcset=\"https:\/\/censonhealth.com\/wp-content\/uploads\/2026\/05\/rpm-770x460.jpg 770w, https:\/\/censonhealth.com\/wp-content\/uploads\/2026\/05\/rpm-18x10.jpg 18w\" sizes=\"(max-width: 770px) 100vw, 770px\" title=\"\"><\/a>\r\n\t\t\t\t         \t\t\t\t\t\t            <div class=\"overlay-post-tag\">\r\n\t\t\t\t\t               \t<a href=\"https:\/\/censonhealth.com\/it\/category\/eldercare\/\" rel=\"category tag\">Assistenza agli anziani<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/home-care\/\" rel=\"category tag\">Assistenza domiciliare<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/remote-patient-monitoring\/\" rel=\"category tag\">Monitoraggio remoto del paziente<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/senior-care\/\" rel=\"category tag\">Assistenza agli anziani<\/a>\t\t\t\t\t            <\/div>\r\n\t\t\t\t        \t\t\t         \t\t<\/div>                                                                                        \r\n\t         \t\t\t\t\t        <div class=\"blog-post-content\">\r\n\t\t\t\t\t\t\t\t\t\t            <div class=\"blog-post-meta\">\r\n\t\t\t\t               \t<ul>\r\n\t\t\t\t\t            \t\t\t\t\t\t               \t<li>\r\n\t\t\t\t\t               \t\t<i class=\"far fa-user\"><\/i>Da \t\t\t\t\t               \t\t<a href=\"https:\/\/censonhealth.com\/it\/author\/censonhealth\/\" rel=\"author\">censonhealth<\/a>\t\t\t\t\t               \t<\/li>\r\n\t\t\t\t\t               \t\t\t\t\t               \t<li><i class=\"far fa-comments\"><\/i>0 Commenti<\/li>\r\n\t\t\t\t\t            \t\t\t\t\t\t            <\/ul>\r\n\t\t\t\t            <\/div>\r\n\t\t\t\t\t\t\t\t\t            <h2><a href=\"https:\/\/censonhealth.com\/it\/my-remote-patient-monitoring-experience\/\">La mia esperienza con il monitoraggio remoto dei pazienti<\/a><\/h2>\r\n\t\t\t\t\t\t\t\t\t\t            <p>With the right technology and a team like Censon in your corner, you can truly say goodbye to hospital<\/p>\r\n\t\t\t\t\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t    \t\t\t<\/div>\r\n\t\t<\/article>\r\n\t<\/div>\r\n\r\n\t   \r\n\t<div class=\"col-lg-4 col-md-6 blog-shortcode\">\r\n\t\t<article id=\"post-15517\" class=\"post-15517 post type-post status-publish format-standard has-post-thumbnail hentry category-home-care category-eldercare category-memory-care category-nursing category-remote-patient-monitoring category-senior-care tag-remote-patient-monitoring\">\r\n\t\t   \t<div class=\"blog-post-item bp-style-two v1\">\r\n\t\t   \t\t\t\t      \t\t\t\t         \t\t<div class=\"blog-post-thumb position-relative\">\r\n\t\t            \t\t<a href=\"https:\/\/censonhealth.com\/it\/the-benefits-of-censon-remote-patient-monitoring-in-60-seconds\/\"><img decoding=\"async\" width=\"770\" height=\"460\" src=\"https:\/\/censonhealth.com\/wp-content\/uploads\/2024\/06\/The-Benefits-of-CENSON-Remote-Patient-Monitoring-in-60-Seconds-770x460.jpg\" class=\"attachment-wellpress-770-460 size-wellpress-770-460 wp-post-image\" alt=\"I vantaggi del monitoraggio remoto del paziente CENSON in 60 secondi\" srcset=\"https:\/\/censonhealth.com\/wp-content\/uploads\/2024\/06\/The-Benefits-of-CENSON-Remote-Patient-Monitoring-in-60-Seconds-770x460.jpg 770w, https:\/\/censonhealth.com\/wp-content\/uploads\/2024\/06\/The-Benefits-of-CENSON-Remote-Patient-Monitoring-in-60-Seconds-18x12.jpg 18w\" sizes=\"(max-width: 770px) 100vw, 770px\" title=\"\"><\/a>\r\n\t\t\t\t         \t\t\t\t\t\t            <div class=\"overlay-post-tag\">\r\n\t\t\t\t\t               \t<a href=\"https:\/\/censonhealth.com\/it\/category\/home-care\/\" rel=\"category tag\">Assistenza domiciliare<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/eldercare\/\" rel=\"category tag\">Assistenza agli anziani<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/memory-care\/\" rel=\"category tag\">Assistenza alla memoria<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/nursing\/\" rel=\"category tag\">Allattamento<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/remote-patient-monitoring\/\" rel=\"category tag\">Monitoraggio remoto del paziente<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/senior-care\/\" rel=\"category tag\">Assistenza agli anziani<\/a>\t\t\t\t\t            <\/div>\r\n\t\t\t\t        \t\t\t         \t\t<\/div>                                                                                        \r\n\t         \t\t\t\t\t        <div class=\"blog-post-content\">\r\n\t\t\t\t\t\t\t\t\t\t            <div class=\"blog-post-meta\">\r\n\t\t\t\t               \t<ul>\r\n\t\t\t\t\t            \t\t\t\t\t\t               \t<li>\r\n\t\t\t\t\t               \t\t<i class=\"far fa-user\"><\/i>Da \t\t\t\t\t               \t\t<a href=\"https:\/\/censonhealth.com\/it\/author\/censonhealth\/\" rel=\"author\">censonhealth<\/a>\t\t\t\t\t               \t<\/li>\r\n\t\t\t\t\t               \t\t\t\t\t               \t<li><i class=\"far fa-comments\"><\/i>0 Commenti<\/li>\r\n\t\t\t\t\t            \t\t\t\t\t\t            <\/ul>\r\n\t\t\t\t            <\/div>\r\n\t\t\t\t\t\t\t\t\t            <h2><a href=\"https:\/\/censonhealth.com\/it\/the-benefits-of-censon-remote-patient-monitoring-in-60-seconds\/\">I vantaggi del monitoraggio remoto del paziente CENSON in 60 secondi<\/a><\/h2>\r\n\t\t\t\t\t\t\t\t\t\t            <p>I vantaggi del monitoraggio remoto del paziente CENSON in 60 secondi. Scoprite come la nostra piattaforma pu\u00f2 migliorare i risultati dei pazienti e<\/p>\r\n\t\t\t\t\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t    \t\t\t<\/div>\r\n\t\t<\/article>\r\n\t<\/div>\r\n\r\n\t   \r\n\t<div class=\"col-lg-4 col-md-6 blog-shortcode\">\r\n\t\t<article id=\"post-15511\" class=\"post-15511 post type-post status-publish format-standard has-post-thumbnail hentry category-eldercare category-home-care category-memory-care category-remote-patient-monitoring category-senior-care tag-remote-patient-monitoring\">\r\n\t\t   \t<div class=\"blog-post-item bp-style-two v1\">\r\n\t\t   \t\t\t\t      \t\t\t\t         \t\t<div class=\"blog-post-thumb position-relative\">\r\n\t\t            \t\t<a href=\"https:\/\/censonhealth.com\/it\/empowering-patients-to-take-control-of-their-health\/\"><img decoding=\"async\" width=\"770\" height=\"460\" src=\"https:\/\/censonhealth.com\/wp-content\/uploads\/2024\/06\/Empowering-Patients-to-Take-Control-of-Their-Health-770x460.jpg\" class=\"attachment-wellpress-770-460 size-wellpress-770-460 wp-post-image\" alt=\"Dare ai pazienti la possibilit\u00e0 di controllare la propria salute\" srcset=\"https:\/\/censonhealth.com\/wp-content\/uploads\/2024\/06\/Empowering-Patients-to-Take-Control-of-Their-Health-770x460.jpg 770w, https:\/\/censonhealth.com\/wp-content\/uploads\/2024\/06\/Empowering-Patients-to-Take-Control-of-Their-Health-18x12.jpg 18w\" sizes=\"(max-width: 770px) 100vw, 770px\" title=\"\"><\/a>\r\n\t\t\t\t         \t\t\t\t\t\t            <div class=\"overlay-post-tag\">\r\n\t\t\t\t\t               \t<a href=\"https:\/\/censonhealth.com\/it\/category\/eldercare\/\" rel=\"category tag\">Assistenza agli anziani<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/home-care\/\" rel=\"category tag\">Assistenza domiciliare<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/memory-care\/\" rel=\"category tag\">Assistenza alla memoria<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/remote-patient-monitoring\/\" rel=\"category tag\">Monitoraggio remoto del paziente<\/a> <a href=\"https:\/\/censonhealth.com\/it\/category\/senior-care\/\" rel=\"category tag\">Assistenza agli anziani<\/a>\t\t\t\t\t            <\/div>\r\n\t\t\t\t        \t\t\t         \t\t<\/div>                                                                                        \r\n\t         \t\t\t\t\t        <div class=\"blog-post-content\">\r\n\t\t\t\t\t\t\t\t\t\t            <div class=\"blog-post-meta\">\r\n\t\t\t\t               \t<ul>\r\n\t\t\t\t\t            \t\t\t\t\t\t               \t<li>\r\n\t\t\t\t\t               \t\t<i class=\"far fa-user\"><\/i>Da \t\t\t\t\t               \t\t<a href=\"https:\/\/censonhealth.com\/it\/author\/censonhealth\/\" rel=\"author\">censonhealth<\/a>\t\t\t\t\t               \t<\/li>\r\n\t\t\t\t\t               \t\t\t\t\t               \t<li><i class=\"far fa-comments\"><\/i>0 Commenti<\/li>\r\n\t\t\t\t\t            \t\t\t\t\t\t            <\/ul>\r\n\t\t\t\t            <\/div>\r\n\t\t\t\t\t\t\t\t\t            <h2><a href=\"https:\/\/censonhealth.com\/it\/empowering-patients-to-take-control-of-their-health\/\">Dare ai pazienti la possibilit\u00e0 di controllare la propria salute<\/a><\/h2>\r\n\t\t\t\t\t\t\t\t\t\t            <p>Consentire ai pazienti di assumere il controllo della propria salute: Monitoraggio remoto del paziente CENSON. Scoprite come la nostra piattaforma pu\u00f2 trasformare il<\/p>\r\n\t\t\t\t\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t    \t\t\t<\/div>\r\n\t\t<\/article>\r\n\t<\/div>\r\n\r\n\t   \t<\/div>\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cb0e9d7 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cb0e9d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b275460\" data-id=\"1b275460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f713492 elementor-widget elementor-widget-heading\" data-id=\"2f713492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Scegliete il vostro piano<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10564b79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10564b79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4b3d1412\" data-id=\"4b3d1412\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-535cb1bd elementor-widget elementor-widget-price-table\" data-id=\"535cb1bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\">\n\t\t\t\t\t\tVITALIZI\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__subheading\">\n\t\t\t\t\t\t\tSDK VITALI\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__currency\">&#128;<\/span>\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__integer-part\">\n\t\t\t\t\t\t1\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__period elementor-typo-excluded\">Per paziente al mese<\/span>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-b8c7e7f\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t&nbsp;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2ce5b14a\" data-id=\"2ce5b14a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94f8caf elementor-widget elementor-widget-price-table\" data-id=\"94f8caf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\">\n\t\t\t\t\t\tPIATTAFORMA\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__subheading\">\n\t\t\t\t\t\t\tPiattaforma RPM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__currency\">&#128;<\/span>\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__integer-part\">\n\t\t\t\t\t\t5\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__period elementor-typo-excluded\">Per paziente al mese<\/span>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-b8c7e7f\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t&nbsp;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"elementor-ribbon\">\n\t\t\t\t<div class=\"elementor-ribbon-inner\">\n\t\t\t\t\tPopolare\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-733e756a\" data-id=\"733e756a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2036eca0 elementor-widget elementor-widget-price-table\" data-id=\"2036eca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\">\n\t\t\t\t\t\tTURNKEY\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__subheading\">\n\t\t\t\t\t\t\tSERVIZIO RPM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__currency\">&#128;<\/span>\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__integer-part\">\n\t\t\t\t\t\t19\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__period elementor-typo-excluded\">Per paziente al mese<\/span>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-b8c7e7f\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t&nbsp;\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2430e43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2430e43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7bf8b3e\" data-id=\"7bf8b3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a30f2e9 elementor-widget elementor-widget-callaction-button\" data-id=\"a30f2e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"callaction-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\r\n        <div class=\"advice-call-area\">\r\n\t        <div class=\"free-quote-wrap\">\r\n\t            <div class=\"row no-gutters align-items-center\">\r\n\t                <div class=\"col-lg-6\">\r\n\t                    <div class=\"free-quote-img\" style=\"background-image:url(https:\/\/censonhealth.com\/wp-content\/uploads\/2021\/03\/offcanvasa_Image_04.jpg)\"><\/div>\r\n\t                <\/div>\r\n\t                <div class=\"col-lg-6\">\r\n\t                    <div class=\"free-quote-content\">\r\n\t                        <h6 class=\"sub-title-style-two\">Avete bisogno di consigli per la consegna del monitoraggio remoto dei pazienti?<\/h6>\r\n\t                        <h2 class=\"title-style-two\"><a href=\"tel:\">Chiama ora<\/a><\/h2>\r\n\t                    <\/div>\r\n\t                <\/div>\r\n\t            <\/div>\r\n\t            \t        <\/div>\r\n        <\/div>\r\n\r\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Smartphone Delivered at home monitoring Remote Patient Monitoring Delivery Services Using simple technology, CENSON&#8217;s smartphone enabled platform provides remote patient monitoring services. This supports improved diagnostic accuracy, earlier intervention, and better health outcomes. 01 Medical Care Build your health and medical care delivery model to meet folks where they live, and using their smartphone. 02 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1069,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-76","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":0,"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/media\/1069"}],"wp:attachment":[{"href":"https:\/\/censonhealth.com\/it\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}